{"id":546,"count":1,"description":"","link":"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/","name":"Microsoft Teams","slug":"microsoft-teams","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microsoft Teams Archive - white duck<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Teams Archive - white duck\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/\" \/>\n<meta property=\"og:site_name\" content=\"white duck\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whiteduck.de\/wp-content\/uploads\/WD-Webpage-Fred-1024x1024px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@whiteduck_gmbh\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/tag\\\/microsoft-teams\\\/\",\"url\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/tag\\\/microsoft-teams\\\/\",\"name\":\"Microsoft Teams Archive - white duck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/tag\\\/microsoft-teams\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/tag\\\/microsoft-teams\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Teams\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/\",\"name\":\"white duck\",\"description\":\"Your Partner for Microsoft Azure &amp; AI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whiteduck.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microsoft Teams Archive - white duck","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Microsoft Teams Archive - white duck","og_url":"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/","og_site_name":"white duck","og_image":[{"width":1024,"height":1024,"url":"https:\/\/whiteduck.de\/wp-content\/uploads\/WD-Webpage-Fred-1024x1024px.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@whiteduck_gmbh","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/","url":"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/","name":"Microsoft Teams Archive - white duck","isPartOf":{"@id":"https:\/\/whiteduck.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/whiteduck.de\/en\/tag\/microsoft-teams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/whiteduck.de\/en\/"},{"@type":"ListItem","position":2,"name":"Microsoft Teams"}]},{"@type":"WebSite","@id":"https:\/\/whiteduck.de\/en\/#website","url":"https:\/\/whiteduck.de\/en\/","name":"white duck","description":"Your Partner for Microsoft Azure &amp; AI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whiteduck.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/whiteduck.de\/en\/wp-json\/wp\/v2\/tags\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whiteduck.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/whiteduck.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/whiteduck.de\/en\/wp-json\/wp\/v2\/posts?tags=546"},{"href":"https:\/\/whiteduck.de\/en\/wp-json\/wp\/v2\/tribe_events?tags=546"},{"href":"https:\/\/whiteduck.de\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}